{"id":72159,"date":"2025-01-28T06:59:48","date_gmt":"2025-01-28T05:59:48","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=72159"},"modified":"2025-01-28T07:00:41","modified_gmt":"2025-01-28T06:00:41","slug":"moncalieri-via-pastrengo-la-poca-sicurezza-vicino-alla-ferrovia-chiunque-puo-accedere","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/01\/28\/moncalieri-via-pastrengo-la-poca-sicurezza-vicino-alla-ferrovia-chiunque-puo-accedere\/","title":{"rendered":"MONCALIERI &#8211; In via Pastrengo la poca sicurezza vicino alla ferrovia: chiunque pu\u00f2 accedere"},"content":{"rendered":"<p>A Borgo San Pietro a Moncalieri chiunque pu\u00f2 accedere ai binari della ferrovia, con una palese mancanza di sicurezza. Alcuni cittadini hanno infatti segnalato come un tratto della linea ferrata non sia per nulla separato dalla strada, di conseguenza vengono a mancare tutti i presupposti di limitazione tra la zona treni e dove passano le vetture oltre ai pedoni. In quella zona sarebbero in atto alcuni cantieri che per\u00f2 al momento non garantiscono sicurezza.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":72158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72159"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72159"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/72158"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72159"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72159"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72159"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72159"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}