{"id":72222,"date":"2025-01-30T21:55:44","date_gmt":"2025-01-30T20:55:44","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=72222"},"modified":"2025-02-03T08:49:31","modified_gmt":"2025-02-03T07:49:31","slug":"trofarello-aperte-le-iscrizioni-ai-nidi-dinfanzia","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/01\/30\/trofarello-aperte-le-iscrizioni-ai-nidi-dinfanzia\/","title":{"rendered":"TROFARELLO &#8211; Aperte le iscrizioni ai nidi d&#8217;infanzia"},"content":{"rendered":"<p>Dal 3\/2\/2025 al 31\/3\/2025 sono aperte le iscrizioni per l&#8217;anno educativo 2025-2026 per il nido d&#8217;infanzia &#8220;Italia 150&#8221; e le due sezioni Primavera presso le scuole dell&#8217;infanzia &#8220;La Pace&#8221; e &#8220;Cardinal Massaia&#8221; a Trofarello<\/p>\n<p>Le iscrizioni sono gestite dalla ditta concessionaria ProGes attraverso il portale iscrizioni dedicato ed accessibile al link<\/p>\n<p>https:\/\/clienti.digilan.it<\/p>\n<p>Per ulteriori informazioni telefonare al n. 331 604 2408<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":51341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72222"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72222"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72222\/revisions"}],"predecessor-version":[{"id":72223,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72222\/revisions\/72223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/51341"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72222"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72222"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72222"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72222"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}