{"id":72306,"date":"2025-02-05T07:17:37","date_gmt":"2025-02-05T06:17:37","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/2025\/02\/05\/nichelino-il-maestro-della-musica-elettronica-al-sonic-park\/"},"modified":"2025-02-05T07:17:55","modified_gmt":"2025-02-05T06:17:55","slug":"nichelino-il-maestro-della-musica-elettronica-al-sonic-park","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/02\/05\/nichelino-il-maestro-della-musica-elettronica-al-sonic-park\/","title":{"rendered":"NICHELINO &#8211; Il maestro della musica elettronica al Sonic Park"},"content":{"rendered":"<p>Al Sonic Park 2025 il maestro della musica elettronica Paul Kalkbrenner. L\u2019evento \u00e8 in calendario sabato 12 luglio alla Palazzina di Caccia di Stupinigi. Dopo gli annunciati live di Gianna Nannini, del maestro Riccardo Muti, dei Dreamtheater e di Jocob Collier, Fondazione Reverse annuncia un altro concerto da non perdere. Un viaggio sonoro travolgente, tra ritmi potenti e atmosfere magnetiche che far\u00e0 ballare sotto le stelle. Nato a Lipsia, Kalkbrenner cresce a Lichtenberg, Berlino Est, prima della caduta del Muro, ed \u00e8 qui che inizia a suonare gi\u00e0 nella prima met\u00e0 degli anni \u201890 nei club giovanili interessandosi alla musica techno insieme con il suo amico Sascha Funke, entrambi grandi ammiratori della band Underground Resistance di Detroit.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":18864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72306"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72306"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/18864"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72306"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72306"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72306"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72306"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}