{"id":72409,"date":"2025-02-11T07:13:11","date_gmt":"2025-02-11T06:13:11","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/02\/11\/moncalieri-aperta-la-manifestazione-di-insteresse-per-il-rifacimento-dellex-tribunale\/"},"modified":"2025-02-11T07:13:13","modified_gmt":"2024-09-14T07:13:13","slug":"moncalieri-aperta-la-manifestazione-di-insteresse-per-il-rifacimento-dellex-tribunale","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/02\/11\/moncalieri-aperta-la-manifestazione-di-insteresse-per-il-rifacimento-dellex-tribunale\/","title":{"rendered":"MONCALIERI &#8211; Aperta la manifestazione di insteresse per il rifacimento dell&#8217;ex tribunale"},"content":{"rendered":"<p>Il Comune di Moncalieri apre alla manifestazione di interesse per il rifacimento dell&#8217;ex tribunale. Chi presenter\u00e0 un progetto sar\u00e0 sorteggiato\u00a0 per un massimo di dieci operatori economici in possesso dei requisiti di ordine generale e di qualificazione per eseguire la progettazione e i lavori.<\/p>\n<p>Con il presente avviso l\u2019Amministrazione intende effettuare un\u2019indagine di mercato, finalizzata all\u2019individuazione di operatori economici da invitare alla successiva procedura negoziata per l\u2019affidamento dei servizi e dei lavori.<\/p>\n<p>Il presente avviso \u00e8 finalizzato esclusivamente a ricevere manifestazioni d\u2019interesse per favorire la partecipazione e la consultazione di operatori economici, in modo non vincolante per la stazione appaltante.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":19305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72409"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72409"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/19305"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72409"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72409"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72409"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72409"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}