{"id":72423,"date":"2025-02-11T21:45:50","date_gmt":"2025-02-11T20:45:50","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/02\/11\/nichelino-auto-incastrata-nel-passaggio-livello\/"},"modified":"2025-02-11T21:45:52","modified_gmt":"2024-09-14T21:45:52","slug":"nichelino-auto-incastrata-nel-passaggio-livello","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/02\/11\/nichelino-auto-incastrata-nel-passaggio-livello\/","title":{"rendered":"NICHELINO &#8211; Auto incastrata nel passaggio a livello"},"content":{"rendered":"<p>Ancora un caso di un automobilista rimasto incastrato con il suo veicolo tra le sbarre della ferrovia a Nichelino. L\u2019incidente ha generato ritardi nella normale circolazione dei treni e caos per le lunghe code che si sono formate in un orario di traffico sostenuto. I civich hanno operato per riportare la situazione alla normalit\u00e0. Il guidatore del mezzo rimasto bloccato tra le sbarre \u00e8 stato multato dalla polizia di Nichelino.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":50969,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72423"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72423"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/50969"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72423"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72423"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72423"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72423"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}