{"id":72440,"date":"2025-02-12T07:07:55","date_gmt":"2025-02-12T06:07:55","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/02\/12\/nichelino-una-sera-stupinigi-guardando-le-stelle-per-san-valentino\/"},"modified":"2025-02-12T07:07:57","modified_gmt":"2024-09-15T07:07:57","slug":"nichelino-una-sera-stupinigi-guardando-le-stelle-per-san-valentino","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/02\/12\/nichelino-una-sera-stupinigi-guardando-le-stelle-per-san-valentino\/","title":{"rendered":"NICHELINO &#8211; Una sera a Stupinigi guardando le stelle per San Valentino"},"content":{"rendered":"<p>Una serata alla scoperta del cielo alla Palazzina di Caccia di Stupinigi La sera di San Valentino, la vista di Venere, insieme a Giove, Marte e Orione, diventa a Stupinigi un evento eccezionale in programma venerd\u00ec 14 febbraio, al tramonto, sulla terrazza della Palazzina di Caccia, verso il parco storico.<\/p>\n<p>&nbsp;<\/p>\n<p>La serata dedicata a Venere prevede un percorso nelle sale alla scoperta di storie, aneddoti e personaggi legati al tema dell\u2019astronomia, come la principessa di Carignano, Giuseppina di Lorena Armagnac (1753-1797), moglie di Vittorio Amedeo di Carignano e nonna di Carlo Alberto: una donna straordinaria per i suoi molteplici interessi, tra cui l\u2019astronomia, di cui la Palazzina conserva un ritratto nell\u2019appartamento di Levante.<\/p>\n<p>&nbsp;<\/p>\n<p>Al termine della visita guidata, una \u201clezione di cielo\u201d nel Salone d\u2019Onore e infine, dalla terrazza, l\u2019osservazione guidata dai telescopi dello staff del Planetario, accompagnata da un calice di vino e una friandise salata, a cura dell\u2019associazione Tutela Baratuciat e Vitigni storici.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":46889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72440"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72440"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/46889"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72440"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72440"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72440"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72440"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}