{"id":72522,"date":"2025-02-18T07:26:24","date_gmt":"2025-02-18T06:26:24","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/02\/18\/pecetto-il-comune-aderisce-alla-campagna-millumino-di-meno\/"},"modified":"2025-02-18T07:26:27","modified_gmt":"2024-09-21T07:26:27","slug":"pecetto-il-comune-aderisce-alla-campagna-millumino-di-meno","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/02\/18\/pecetto-il-comune-aderisce-alla-campagna-millumino-di-meno\/","title":{"rendered":"PECETTO &#8211; Il Comune aderisce alla campagna &#8216;M&#8217;illumino di meno&#8217;"},"content":{"rendered":"<p>Il Comune di Pecetto Torinese aderisce alla campagna di sensibilizzazione di &#8220;M&#8217;illumino di meno&#8221;, spegnendo dalle ore 18.00 del 16 febbraio 2025 al giorno successivo, delle luci del giardino e del Palazzo Comunale e di parte di Piazza della Parrocchia &#8211; Piazza Roma e parte centrale di Via Umberto I.<\/p>\n<p>&#8220;Invitiamo a spegnere le luci non essenziali domenica 16 febbraio e dato che un giorno solo non basta pi\u00f9, ci sar\u00e0 tempo fino al 21 febbraio per organizzare le vostre iniziative&#8221;, spiegano dal Comune.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":52747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72522"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72522"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/52747"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72522"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72522"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72522"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72522"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}