{"id":73128,"date":"2025-03-20T21:52:24","date_gmt":"2025-03-20T20:52:24","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/03\/20\/vinovo-workshop-di-kintsugi\/"},"modified":"2025-03-21T05:23:34","modified_gmt":"2024-10-22T05:23:34","slug":"vinovo-workshop-di-kintsugi","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/03\/20\/vinovo-workshop-di-kintsugi\/","title":{"rendered":"VINOVO &#8211; Workshop di Kintsugi"},"content":{"rendered":"<p>A Vinovo il workshop di kintsugi con la maestra Aiko Zushi. Iniziativa pensata per avvicinare alla pratica del kintsugi le persone che nutrono un profondo interesse per la cultura giapponese. Attraverso un seminario con laboratorio pratico, i partecipanti potranno familiarizzare con la lacca urushi, il materiale fondamentale usato in questo tipo di tecnica, e sperimenteranno l&#8217;ultima fase del processo di restauro, ovvero la finitura con polvere d&#8217;oro (maki-e). Le materie prime e il piatto di ceramica utilizzati arrivano direttamente dal Giappone.<\/p>\n<p>Costo di partecipazione 50\u20ac<\/p>\n<p>Quando: Sabato 5 aprile 2025 ore 15.30<\/p>\n<p>Prenotazioni tel. 0119620413<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":73126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73128"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=73128"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73128\/revisions"}],"predecessor-version":[{"id":73130,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73128\/revisions\/73130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/73126"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=73128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=73128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=73128"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=73128"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=73128"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=73128"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=73128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}