{"id":73204,"date":"2025-03-25T21:55:44","date_gmt":"2025-03-25T20:55:44","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/03\/25\/elezioni-le-comunali-il-25-26-maggio\/"},"modified":"2025-03-25T21:55:47","modified_gmt":"2024-10-26T21:55:47","slug":"elezioni-le-comunali-il-25-26-maggio","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/03\/25\/elezioni-le-comunali-il-25-26-maggio\/","title":{"rendered":"ELEZIONI &#8211; Le Comunali il 25-26 maggio"},"content":{"rendered":"<p>Via libera del Consiglio dei ministri al decreto elezioni che consentir\u00e0 di votare in due giorni (domenica dalle 7 alle 23 e luned\u00ec dalle 7 alle 15). La data per il primo turno delle comunali \u00e8 stata individuata nel 25-26 maggio mentre l\u2019election day con i referendum sar\u00e0 nelle date dei ballottaggi, l\u20198 e 9 giugno.<\/p>\n<p>&nbsp;<\/p>\n<p>Una novit\u00e0 \u00e8 arrivata per studenti e lavoratori fuori sede. Anche a seguito delle richieste dei promotori e delle opposizioni, il governo ha inserito nella bozza del decreto una norma per permettere a chi abita lontano dalla propria citt\u00e0 di residenza di votare per il referendum (non per le elezioni comunali).<\/p>\n<p>&nbsp;<\/p>\n<p>Andranno al voto 124 comuni appartenenti alle regioni a statuto ordinario e alle regioni a statuto speciale Sardegna e Sicilia.<\/p>\n<p>&nbsp;<\/p>\n<p>I referendum sono cinque, quattro promossi dalla Cgil sul lavoro (jobs act con la reintroduzione del reintegro in caso di licenziamento illegittimo, indennit\u00e0 per licenziamento nelle pmi, contratti a termine per cui si chiede l\u2019obbligo di causale, responsabilit\u00e0 del committente in caso di infortuni sul lavoro), e uno per dimezzare da dieci a cinque anni gli anni di residenza in Italia per ottenere la cittadinanza.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":2888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73204"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=73204"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/2888"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=73204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=73204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=73204"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=73204"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=73204"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=73204"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=73204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}