{"id":73235,"date":"2025-03-27T06:38:10","date_gmt":"2025-03-27T05:38:10","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2025\/03\/27\/nichelino-si-concludono-sabato-le-iniziative-per-la-marcia-della-pace\/"},"modified":"2025-03-27T06:38:12","modified_gmt":"2024-10-28T06:38:12","slug":"nichelino-si-concludono-sabato-le-iniziative-per-la-marcia-della-pace","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/03\/27\/nichelino-si-concludono-sabato-le-iniziative-per-la-marcia-della-pace\/","title":{"rendered":"NICHELINO &#8211; Si concludono sabato le iniziative per la marcia della pace"},"content":{"rendered":"<p>Si concludono sabato con la Marcia della Pace le iniziative messe in calendario per costruire un futuro di pace. Venerd\u00ec 28 marzo, ore 21, nel salone parrocchiale della Madonna della Fiducia (piazza Moro 2) si terr\u00e0 la proiezione del film \u201cNon conosci Papicha\u201d di Mounia Meddour, a cura del Gruppo Missionario della Parrocchia Madonna della Fiducia.<\/p>\n<p>&nbsp;<\/p>\n<p>Sabato 29 marzo Marcia della Pace, giunta quest\u2019anno alla quinta edizione. Per i partecipanti il ritrovo \u00e8 in piazza Camandona alle 14.30. Il corteo sfiler\u00e0 lungo via Torino con arrivo in piazza G. Di Vittorio dove ci saranno interventi, letture degli studenti delle scuole nichelinesi e musica.<\/p>\n<p>&nbsp;<\/p>\n<p>Infine, venerd\u00ec 4 aprile, ore 19.30, nel salone dell\u2019oratorio Alex Tamburello della parrocchia Madonna della Fiducia, ci sar\u00e0 la presentazione del libro \u201cViaggi di sola andata\u201d di e con Davide Demichelis. A seguire apericena con i sapori del mondo<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":45796,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73235"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=73235"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/73235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/45796"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=73235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=73235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=73235"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=73235"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=73235"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=73235"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=73235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}