{"id":80878,"date":"2026-05-13T13:54:09","date_gmt":"2026-05-13T11:54:09","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2026\/05\/13\/moncalieri-salone-off-con-matteo-bussola\/"},"modified":"2026-05-13T13:54:14","modified_gmt":"2025-07-17T13:54:14","slug":"moncalieri-salone-off-con-matteo-bussola","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2026\/05\/13\/moncalieri-salone-off-con-matteo-bussola\/","title":{"rendered":"MONCALIERI &#8211; Salone Off con Matteo Bussola"},"content":{"rendered":"<p>Sabato 16 alle 17 in occasione del Salone OFF del Salone Internazionale del Libro, Matteo Bussola presenta in Biblioteca a Moncalieri il romanzo \u201cLa luce degli incendi a dicembre\u201d.<\/p>\n<p>Una storia intensa, ambientata a partire da un incontro inatteso: un treno affollato, due sconosciuti seduti uno di fronte all\u2019altra, una fuga, un ritorno e parole impreviste che aprono nuove possibilit\u00e0.<\/p>\n<p>L\u2019autore dialogher\u00e0 con Paola Dar\u00f2.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":51062,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/80878"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=80878"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/80878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/51062"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=80878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=80878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=80878"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=80878"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=80878"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=80878"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=80878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}