{"id":82050,"date":"2026-07-15T07:27:05","date_gmt":"2026-07-15T05:27:05","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/2026\/07\/15\/moncalieri-nuova-escursione-organizzata-dal-cai-20260715-0527-054991\/"},"modified":"2026-07-15T07:30:28","modified_gmt":"2025-09-18T07:30:28","slug":"moncalieri-nuova-escursione-organizzata-dal-cai-20260715-0527-054991","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2026\/07\/15\/moncalieri-nuova-escursione-organizzata-dal-cai-20260715-0527-054991\/","title":{"rendered":"MONCALIERI &#8211; Nuova escursione organizzata dal Cai"},"content":{"rendered":"<p>Il Club Alpino Italiano di Moncalieri organizza, domenica 19 luglio, un\u2019escursione al Monte Chaberton (3.131 m) con partenza dal Monginevro. Si ricorda che, la segreteria del C.A.I. \u00e8 aperta in Piazza Marconi 1 a Testona il mercoled\u00ec dalle ore 21 alle 22.30. Info: tel.: 331\/349.20.48; mail: cai.sez.moncalieri@gmail.com.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":2242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/82050"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=82050"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/82050\/revisions"}],"predecessor-version":[{"id":82053,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/82050\/revisions\/82053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/2242"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=82050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=82050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=82050"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=82050"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=82050"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=82050"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=82050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}